
{"id":1249,"date":"2026-03-17T16:34:06","date_gmt":"2026-03-17T16:34:06","guid":{"rendered":"https:\/\/ipasrdc.org\/?p=1249"},"modified":"2026-03-17T16:45:57","modified_gmt":"2026-03-17T16:45:57","slug":"clubs-scolaires-dssr-au-kasai-la-connaissance-des-droits-pour-preserver-la-vie-des-eleves","status":"publish","type":"post","link":"https:\/\/ipasrdc.org\/fr\/clubs-scolaires-dssr-au-kasai-la-connaissance-des-droits-pour-preserver-la-vie-des-eleves\/","title":{"rendered":"Clubs scolaires DSSR au Kasa\u00ef : la connaissance des droits pour pr\u00e9server  la vie des \u00e9l\u00e8ves"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Dans la province du Kasa\u00ef, une \u00e9valuation de l\u2019\u00e9cosyst\u00e8me CTS (Child Marriage, Teen Pregnancy, School Dropout) a conduit \u00e0 la cr\u00e9ation de clubs scolaires dans six \u00e9tablissements\u00a0: l\u2019Institut de Tshikapa, l\u2019Institut Maker Mwangu, l\u2019Institut Tshikunga, l\u2019Institut Diketemene, l\u2019Institut Kene et le Lyc\u00e9e Disanka.<\/p>\n<p>En r\u00e9v\u00e9lant une situation pr\u00e9occupante marqu\u00e9e par une forte pr\u00e9valence du mariage pr\u00e9coce, des grossesses chez les adolescentes et du d\u00e9crochage scolaire, cette \u00e9valuation a mis en lumi\u00e8re des probl\u00e9matiques \u00e9troitement li\u00e9es qui freinent l\u2019\u00e9panouissement des jeunes filles.<\/p>\n<p>Les donn\u00e9es de l\u2019enqu\u00eate MICS 2017\u20112018 indiquent que 54\u00a0% des femmes de 20 \u00e0 24 ans ont \u00e9t\u00e9 mari\u00e9es avant l\u2019\u00e2ge de 18 ans au Kasa\u00ef, contre 29\u00a0% au niveau national. Entre 2021 et 2024, 425 cas de mariages pr\u00e9coces ont \u00e9t\u00e9 enregistr\u00e9s dans la province, impliquant majoritairement des filles \u00e2g\u00e9es de 15 \u00e0 17 ans.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h2><strong>Les clubs DSSR : des espaces s\u00fbrs et transformateurs<\/strong><\/h2>\n<p>En renfor\u00e7ant les connaissances des \u00e9l\u00e8ves \u00e0 travers des formations structur\u00e9es, en d\u00e9veloppant les comp\u00e9tences des enseignants pour animer des sessions sur l\u2019\u00e9ducation sexuelle compl\u00e8te et en promouvant l\u2019engagement des jeunes dans la sensibilisation de leurs pairs, ces clubs scolaires se sont impos\u00e9s comme des espaces s\u00fbrs et transformateurs.<\/p>\n<p>Chaque club, compos\u00e9 de vingt membres (douze filles et huit gar\u00e7ons), est form\u00e9, avec l\u2019appui technique de Ipas RDC, pendant trois mois sur huit modules allant de la pr\u00e9vention des IST\/VIH aux grossesses et mariages pr\u00e9coces, en passant par les relations humaines, le consentement, la notion de genre et l\u2019engagement communautaire.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ipasrdc.org\/wp-content\/uploads\/2026\/03\/IMG_3010-0-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbIMG_3010 0&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>En formant cent vingt \u00e9l\u00e8ves et en les amenant \u00e0 restituer leurs acquis aupr\u00e8s de mille quatre cents camarades, en organisant un concours interscolaire qui a mobilis\u00e9 pr\u00e8s de six mille participants et en consacrant l\u2019Institut Tshikunga champion du Troph\u00e9e Makoki ya Mwasi 2025, cette initiative a d\u00e9montr\u00e9 son efficacit\u00e9.<\/p>\n<p>Cette ann\u00e9e, la deuxi\u00e8me \u00e9dition (2025\u20112026) a \u00e9t\u00e9 officiellement lanc\u00e9e au Lyc\u00e9e Disanka, en pr\u00e9sence des autorit\u00e9s scolaires provinciales, des enseignants, des parents et de plus de huit cents \u00e9l\u00e8ves, marquant une nouvelle \u00e9tape dans l\u2019engagement communautaire pour la sant\u00e9 sexuelle et reproductive des jeunes.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ipasrdc.org\/wp-content\/uploads\/2026\/03\/IMG_7882-0-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbIMG_7882 0&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h2><strong>L\u2019\u00e9ducation des adolescentes : un d\u00e9fi majeur<\/strong><\/h2>\n<p>Les clubs scolaires DSSR s\u2019inscrivent dans une r\u00e9ponse \u00e0 une r\u00e9alit\u00e9 pr\u00e9occupante. En RDC, 66,3\u00a0% des \u00e9l\u00e8ves ayant abandonn\u00e9 l\u2019\u00e9cole en 2017\u20112018 \u00e9taient des filles, la grossesse \u00e9tant l\u2019un des principaux motifs. Une enqu\u00eate men\u00e9e \u00e0 Kinshasa par le Service National Femme et D\u00e9veloppement du Minist\u00e8re du Genre, Famille et Enfant a montr\u00e9 que, malgr\u00e9 la loi autorisant les filles enceintes \u00e0 poursuivre leur scolarit\u00e9, les obstacles persistent.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>En 2013 d\u00e9j\u00e0, <a href=\"https:\/\/edu-nc.gouv.cd\/wp-content\/uploads\/2022\/09\/ETUDE-SUR-LOPPERATIONNALISATION-DES-STRATEGIES-DE-REDUCTION-DES-ABANDONS-SCOLAIRE-EN-RDC-le-12.03.2020.pdf\">les taux d\u2019abandon scolaire<\/a> d\u00e9passaient 22\u00a0% en premi\u00e8re et derni\u00e8re ann\u00e9e du primaire. Sur pr\u00e8s de 3\u00a0millions d\u2019enfants inscrits en premi\u00e8re ann\u00e9e, environ 700\u00a0000 avaient quitt\u00e9 le syst\u00e8me en cours ou \u00e0 la fin de l\u2019ann\u00e9e. De plus, 305\u00a0000 \u00e9l\u00e8ves avaient abandonn\u00e9 avant la fin de la 6\u1d49 ann\u00e9e sur 1\u00a0370\u00a0000 inscrits. Ces chiffres illustrent l\u2019ampleur du probl\u00e8me et la n\u00e9cessit\u00e9 d\u2019interventions coordonn\u00e9es.<\/p>\n<p>Malgr\u00e9 ces r\u00e9alit\u00e9s persistantes, les clubs scolaires ont servi de leviers pour \u00e9veiller les consciences des \u00e9l\u00e8ves, comme le t\u00e9moigne Joseph Muyaya, pr\u00e9fet de l\u2019Institut Maker Mwangu\u00a0:<\/p>\n<blockquote>\n<h2><em>\u00ab<strong>\u00a0Le constat que nous avons fait \u00e0 la fin de l\u2019ann\u00e9e est remarquable, nous avons enregistr\u00e9 z\u00e9ro cas de grossesse chez les filles. Ce fut une ann\u00e9e o\u00f9 nous \u00e9tions particuli\u00e8rement heureux<\/strong>.\u00a0\u00bb<\/em><\/h2>\n<\/blockquote>\n<p>Au\u2011del\u00e0 de ce r\u00e9sultat, il a soulign\u00e9 un changement de comportement,\u00a0les filles ne se plaignaient plus de harc\u00e8lements et \u00e9taient d\u00e9sormais capables de se prot\u00e9ger, de faire valoir leurs droits et de les ma\u00eetriser.<\/p>\n<h2><strong>Vers une g\u00e9n\u00e9ration consciente et r\u00e9siliente<\/strong><\/h2>\n<p>Port\u00e9s par Ipas RDC avec l\u2019appui du projet Norad, les clubs scolaires DSSR d\u00e9montrent que l\u2019engagement communautaire ne se limite pas \u00e0 sensibiliser. Il pr\u00e9pare concr\u00e8tement les adolescentes et adolescents \u00e0 conna\u00eetre leurs droits, \u00e0 les d\u00e9fendre et \u00e0 les mettre en pratique.<\/p>\n<p>La cl\u00f4ture des activit\u00e9s est pr\u00e9vue en mai avec le concours interscolaire \u00ab\u00a0Makoki Ya Mwasi\u00a0\u00bb deuxi\u00e8me \u00e9dition, une c\u00e9l\u00e9bration de l\u2019intelligence, du courage, de la cr\u00e9ativit\u00e9 et de l\u2019engagement des \u00e9l\u00e8ves.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans la province du Kasa\u00ef, une \u00e9valuation de l\u2019\u00e9cosyst\u00e8me CTS (Child Marriage, Teen Pregnancy, School Dropout) a conduit \u00e0 la cr\u00e9ation de clubs scolaires dans six \u00e9tablissements\u00a0: l\u2019Institut de Tshikapa, l\u2019Institut Maker Mwangu, l\u2019Institut Tshikunga, l\u2019Institut Diketemene, l\u2019Institut Kene et le Lyc\u00e9e Disanka. En r\u00e9v\u00e9lant une situation pr\u00e9occupante marqu\u00e9e par une forte pr\u00e9valence du mariage pr\u00e9coce, des grossesses chez les adolescentes et du d\u00e9crochage scolaire, cette \u00e9valuation a mis en lumi\u00e8re des probl\u00e9matiques \u00e9troitement li\u00e9es qui freinent l\u2019\u00e9panouissement des jeunes filles. Les donn\u00e9es de l\u2019enqu\u00eate MICS 2017\u20112018 indiquent que 54\u00a0% des femmes de 20 \u00e0 24 ans ont \u00e9t\u00e9 mari\u00e9es avant l\u2019\u00e2ge de 18 ans au Kasa\u00ef, contre 29\u00a0% au niveau national. Entre 2021 et 2024, 425 cas de mariages pr\u00e9coces ont \u00e9t\u00e9 enregistr\u00e9s dans la province, impliquant majoritairement des filles \u00e2g\u00e9es de 15 \u00e0 17 ans.Les clubs DSSR : des espaces s\u00fbrs et transformateurs En renfor\u00e7ant les connaissances des \u00e9l\u00e8ves \u00e0 travers des formations structur\u00e9es, en d\u00e9veloppant les comp\u00e9tences des enseignants pour animer des sessions sur l\u2019\u00e9ducation sexuelle compl\u00e8te et en promouvant l\u2019engagement des jeunes dans la sensibilisation de leurs pairs, ces clubs scolaires se sont impos\u00e9s comme des espaces s\u00fbrs et transformateurs. Chaque club, compos\u00e9 de vingt membres [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1250,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"work-area":[24],"topic":[28,33,19,30],"class_list":["post-1249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engagement-communautaire","work-area-community-engagement","topic-cts-nexus","topic-gender-based-violence","topic-sexuality-education","topic-youth-engagement"],"_links":{"self":[{"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/posts\/1249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/comments?post=1249"}],"version-history":[{"count":0,"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/posts\/1249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/media\/1250"}],"wp:attachment":[{"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/media?parent=1249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/categories?post=1249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/tags?post=1249"},{"taxonomy":"work-area","embeddable":true,"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/work-area?post=1249"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/ipasrdc.org\/fr\/wp-json\/wp\/v2\/topic?post=1249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}